{"id":8290,"date":"2022-02-23T14:18:33","date_gmt":"2022-02-23T13:18:33","guid":{"rendered":"http:\/\/www.krakauer-haus.de\/?post_type=tribe_events&#038;p=8290"},"modified":"2022-04-25T16:28:53","modified_gmt":"2022-04-25T14:28:53","slug":"polnische-filmwoche-2022","status":"publish","type":"tribe_events","link":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/event\/polnische-filmwoche-2022\/","title":{"rendered":"POLNISCHE FILMWOCHE 2022"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>12. &#8211; 18. Mai, Cinecitta<\/p>\n","protected":false},"author":2,"featured_media":8460,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[31],"class_list":["post-8290","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-film","cat_film"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/tribe_events\/8290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/comments?post=8290"}],"version-history":[{"count":1,"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/tribe_events\/8290\/revisions"}],"predecessor-version":[{"id":8291,"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/tribe_events\/8290\/revisions\/8291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/media\/8460"}],"wp:attachment":[{"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/media?parent=8290"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/tags?post=8290"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.krakauer-haus.de\/kh-test\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=8290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}